{"id":257,"date":"2022-01-25T12:17:02","date_gmt":"2022-01-25T11:17:02","guid":{"rendered":"https:\/\/www.villabordoni.com\/room-suite\/colognole-suite\/"},"modified":"2026-03-08T13:30:06","modified_gmt":"2026-03-08T12:30:06","slug":"colognole-suite","status":"publish","type":"page","link":"https:\/\/www.villabordoni.com\/it\/camere-suite\/colognole-suite\/","title":{"rendered":"Colognole Suite"},"content":{"rendered":"\n<p> <\/p>\n\n\n\n<p>Situata all\u2019ultimo piano della villa, gi\u00e0 una torre fortificata con origine nel XI secolo, Colognole \u00e8 stata trasformata in un\u2019ampia suite dallo stile univoco &#8211; lussuoso, ma ironico e discreto.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Situata all\u2019ultimo piano della villa, gi\u00e0 una torre fortificata con origine nel XI secolo, <strong>Colognole <\/strong>\u00e8 stata trasformata in un\u2019ampia suite dallo stile univoco &#8211; lussuoso, ma ironico e discreto.<\/p>\n\n\n\n<p>Riccardo Barthel, il noto architetto d&#8217;interni che ha dato vita allo stile di Villa Bordoni, ha infatti lasciato libero sfogo alla sua fantasia e vasta esperienza. Qui, pi\u00f9 che in qualsiasi altra camera, \u00e8 riuscito a firmare gli interni con le sue note &#8220;trasformazioni&#8221; &#8211; ed ecco che un pollaio trovato abbandonato nella propriet\u00e0 diventa l\u2019ornamento centrale del soggiorno, e un vecchio cesto arrugginito, capovolto, si trasforma in un lampadario che illumina il tavolo della suite.<\/p>\n\n\n\n<p>La suite \u00e8 dotata di un grande televisore 3D HD, lettore BluRay, cassa Bluetooth, Wi-Fi, mini bar, telefono, cassaforte, aria condizionata e riscaldamento. Un\u2019altra televisione e un lettore DVD sono presenti nel soggiorno.<\/p>\n\n\n\n<p>Nella suite, che ha un&#8217;area totale di 37 mq, \u00e8 presente un grande letto matrimoniale; il bagno, di 6mq, ha un\u2019ampia doccia realizzata su misura.<\/p>\n\n\n\n<p>Un terzo letto pu\u00f2 essere aggiunto nel salotto della suite.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Situata all\u2019ultimo piano della villa, gi\u00e0 una torre fortificata con origine nel XI secolo, Colognole \u00e8 stata trasformata in un\u2019ampia suite dallo stile univoco &#8211; lussuoso, ma ironico e discreto.<\/p>\n","protected":false},"author":1,"featured_media":1474,"parent":57,"menu_order":23,"comment_status":"closed","ping_status":"closed","template":"template-room-details.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-257","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colognole Suite | Suite di Lusso nel Chianti - Villa Bordoni<\/title>\n<meta name=\"description\" content=\"La Colognole Suite: ampia suite di lusso dallo stile unico, lussuoso e ironico. L&#039;esperienza pi\u00f9 esclusiva tra le camere di Villa Bordoni nel Chianti Classico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.villabordoni.com\/it\/camere-suite\/colognole-suite\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colognole Suite | Suite di Lusso nel Chianti - Villa Bordoni\" \/>\n<meta property=\"og:description\" content=\"La Colognole Suite: ampia suite di lusso dallo stile unico, lussuoso e ironico. L&#039;esperienza pi\u00f9 esclusiva tra le camere di Villa Bordoni nel Chianti Classico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.villabordoni.com\/it\/camere-suite\/colognole-suite\/\" \/>\n<meta property=\"og:site_name\" content=\"Villa Bordoni Chianti Hotel\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-08T12:30:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.villabordoni.com\/wp-content\/uploads\/2022\/02\/Colognolebis-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.villabordoni.com\\\/it\\\/camere-suite\\\/colognole-suite\\\/\",\"url\":\"https:\\\/\\\/www.villabordoni.com\\\/it\\\/camere-suite\\\/colognole-suite\\\/\",\"name\":\"Colognole Suite | Suite di Lusso nel Chianti - Villa Bordoni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.villabordoni.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.villabordoni.com\\\/it\\\/camere-suite\\\/colognole-suite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.villabordoni.com\\\/it\\\/camere-suite\\\/colognole-suite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.villabordoni.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Colognolebis-2.jpg\",\"datePublished\":\"2022-01-25T11:17:02+00:00\",\"dateModified\":\"2026-03-08T12:30:06+00:00\",\"description\":\"La Colognole Suite: ampia suite di lusso dallo stile unico, lussuoso e ironico. L'esperienza pi\u00f9 esclusiva tra le camere di Villa Bordoni nel Chianti Classico.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.villabordoni.com\\\/it\\\/camere-suite\\\/colognole-suite\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.villabordoni.com\\\/it\\\/camere-suite\\\/colognole-suite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.villabordoni.com\\\/it\\\/camere-suite\\\/colognole-suite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.villabordoni.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Colognolebis-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.villabordoni.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Colognolebis-2.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.villabordoni.com\\\/it\\\/camere-suite\\\/colognole-suite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.villabordoni.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Camere &#038; Suite\",\"item\":\"https:\\\/\\\/www.villabordoni.com\\\/it\\\/camere-suite\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Colognole Suite\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.villabordoni.com\\\/#website\",\"url\":\"https:\\\/\\\/www.villabordoni.com\\\/\",\"name\":\"Villa Bordoni Chianti Hotel\",\"description\":\"Boutique hotel in the heart of Tuscany\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.villabordoni.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colognole Suite | Suite di Lusso nel Chianti - Villa Bordoni","description":"La Colognole Suite: ampia suite di lusso dallo stile unico, lussuoso e ironico. L'esperienza pi\u00f9 esclusiva tra le camere di Villa Bordoni nel Chianti Classico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.villabordoni.com\/it\/camere-suite\/colognole-suite\/","og_locale":"it_IT","og_type":"article","og_title":"Colognole Suite | Suite di Lusso nel Chianti - Villa Bordoni","og_description":"La Colognole Suite: ampia suite di lusso dallo stile unico, lussuoso e ironico. L'esperienza pi\u00f9 esclusiva tra le camere di Villa Bordoni nel Chianti Classico.","og_url":"https:\/\/www.villabordoni.com\/it\/camere-suite\/colognole-suite\/","og_site_name":"Villa Bordoni Chianti Hotel","article_modified_time":"2026-03-08T12:30:06+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.villabordoni.com\/wp-content\/uploads\/2022\/02\/Colognolebis-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.villabordoni.com\/it\/camere-suite\/colognole-suite\/","url":"https:\/\/www.villabordoni.com\/it\/camere-suite\/colognole-suite\/","name":"Colognole Suite | Suite di Lusso nel Chianti - Villa Bordoni","isPartOf":{"@id":"https:\/\/www.villabordoni.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.villabordoni.com\/it\/camere-suite\/colognole-suite\/#primaryimage"},"image":{"@id":"https:\/\/www.villabordoni.com\/it\/camere-suite\/colognole-suite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.villabordoni.com\/wp-content\/uploads\/2022\/02\/Colognolebis-2.jpg","datePublished":"2022-01-25T11:17:02+00:00","dateModified":"2026-03-08T12:30:06+00:00","description":"La Colognole Suite: ampia suite di lusso dallo stile unico, lussuoso e ironico. L'esperienza pi\u00f9 esclusiva tra le camere di Villa Bordoni nel Chianti Classico.","breadcrumb":{"@id":"https:\/\/www.villabordoni.com\/it\/camere-suite\/colognole-suite\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.villabordoni.com\/it\/camere-suite\/colognole-suite\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.villabordoni.com\/it\/camere-suite\/colognole-suite\/#primaryimage","url":"https:\/\/www.villabordoni.com\/wp-content\/uploads\/2022\/02\/Colognolebis-2.jpg","contentUrl":"https:\/\/www.villabordoni.com\/wp-content\/uploads\/2022\/02\/Colognolebis-2.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.villabordoni.com\/it\/camere-suite\/colognole-suite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.villabordoni.com\/it\/"},{"@type":"ListItem","position":2,"name":"Camere &#038; Suite","item":"https:\/\/www.villabordoni.com\/it\/camere-suite\/"},{"@type":"ListItem","position":3,"name":"Colognole Suite"}]},{"@type":"WebSite","@id":"https:\/\/www.villabordoni.com\/#website","url":"https:\/\/www.villabordoni.com\/","name":"Villa Bordoni Chianti Hotel","description":"Boutique hotel in the heart of Tuscany","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.villabordoni.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.villabordoni.com\/it\/wp-json\/wp\/v2\/pages\/257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.villabordoni.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.villabordoni.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.villabordoni.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.villabordoni.com\/it\/wp-json\/wp\/v2\/comments?post=257"}],"version-history":[{"count":9,"href":"https:\/\/www.villabordoni.com\/it\/wp-json\/wp\/v2\/pages\/257\/revisions"}],"predecessor-version":[{"id":1482,"href":"https:\/\/www.villabordoni.com\/it\/wp-json\/wp\/v2\/pages\/257\/revisions\/1482"}],"up":[{"embeddable":true,"href":"https:\/\/www.villabordoni.com\/it\/wp-json\/wp\/v2\/pages\/57"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.villabordoni.com\/it\/wp-json\/wp\/v2\/media\/1474"}],"wp:attachment":[{"href":"https:\/\/www.villabordoni.com\/it\/wp-json\/wp\/v2\/media?parent=257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}